{"id":2748,"date":"2014-04-07T00:00:00","date_gmt":"2014-04-07T00:00:00","guid":{"rendered":"https:\/\/www.redesalvatoriana.org.br\/bomconselho\/blog\/2014\/04\/07\/exposicao-ready-made-isso-e-arte\/"},"modified":"2014-04-07T00:00:00","modified_gmt":"2014-04-07T00:00:00","slug":"exposicao-ready-made-isso-e-arte","status":"publish","type":"post","link":"https:\/\/www.redesalvatoriana.org.br\/bomconselho\/blog\/2014\/04\/07\/exposicao-ready-made-isso-e-arte\/","title":{"rendered":"Exposi\u00e7\u00e3o Ready Made: Isso \u00e9 Arte?"},"content":{"rendered":"<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Est&atilde;o espalhadas por todo o Col&eacute;gio, obras criadas pelos alunos do 3 &ordm; ano do Ensino M&eacute;dio.<br \/>Inventado pelo artista Marcel Duchamp, o Ready Made &eacute; a apropria&ccedil;&atilde;o que o artista faz de objetos utilit&aacute;rios produzidos industrialmente, com a inten&ccedil;&atilde;o de inseri-los, praticamente sem altera&ccedil;&otilde;es, no contexto art&iacute;stico. O artista n&atilde;o &eacute; respons&aacute;vel pela cria&ccedil;&atilde;o do objeto em nenhuma etapa de sua fabrica&ccedil;&atilde;o industrial, ele apenas seleciona. muitas vezes ao acaso, objetos prontos para atribuir a eles o status de obra de arte. Os Ready Mades questionam o mito do artista como um g&ecirc;nio criador e tamb&eacute;m levam &agrave; percep&ccedil;&atilde;o de que, do ponto de vista da arte, um objeto pode assumir diferentes significados, dependendo do contexto e do ambiente em que &eacute; inserido. Esse tipo de arte criada por Duchamp rompe com a tradi&ccedil;&atilde;o do autor enquanto &uacute;nico criador da obra, mas reivindica para si a autoridade de determinar o que &eacute; ou n&atilde;o obra de arte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Est&atilde;o espalhadas por todo o Col&eacute;gio, obras criadas pelos alunos do 3 &ordm; ano do Ensino M&eacute;dio.Inventado pelo artista Marcel Duchamp, o Ready Made &eacute; a apropria&ccedil;&atilde;o que o artista faz de objetos utilit&aacute;rios produzidos industrialmente, com a inten&ccedil;&atilde;o de inseri-los, praticamente sem altera&ccedil;&otilde;es, no contexto art&iacute;stico. O artista n&atilde;o &eacute; respons&aacute;vel pela cria&ccedil;&atilde;o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2749,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/www.redesalvatoriana.org.br\/bomconselho\/blog\/wp-json\/wp\/v2\/posts\/2748"}],"collection":[{"href":"https:\/\/www.redesalvatoriana.org.br\/bomconselho\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redesalvatoriana.org.br\/bomconselho\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redesalvatoriana.org.br\/bomconselho\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redesalvatoriana.org.br\/bomconselho\/blog\/wp-json\/wp\/v2\/comments?post=2748"}],"version-history":[{"count":0,"href":"https:\/\/www.redesalvatoriana.org.br\/bomconselho\/blog\/wp-json\/wp\/v2\/posts\/2748\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redesalvatoriana.org.br\/bomconselho\/blog\/wp-json\/wp\/v2\/media\/2749"}],"wp:attachment":[{"href":"https:\/\/www.redesalvatoriana.org.br\/bomconselho\/blog\/wp-json\/wp\/v2\/media?parent=2748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redesalvatoriana.org.br\/bomconselho\/blog\/wp-json\/wp\/v2\/categories?post=2748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redesalvatoriana.org.br\/bomconselho\/blog\/wp-json\/wp\/v2\/tags?post=2748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}